{"id":55546,"date":"2023-10-26T23:47:11","date_gmt":"2023-10-26T23:47:11","guid":{"rendered":"https:\/\/chemeng.technion.ac.il\/?p=55546"},"modified":"2023-10-26T23:47:14","modified_gmt":"2023-10-26T23:47:14","slug":"seminar-by-zihua-chen","status":"publish","type":"post","link":"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/","title":{"rendered":"Seminar by     Zihua Chen"},"content":{"rendered":"\n<p>Seminar by Zihua Chen<strong> <\/strong>on: <\/p>\n\n\n\n<p><a href=\"https:\/\/chemeng.technion.ac.il\/wp-content\/uploads\/2023\/10\/Abstract_Zihua_midseminar_October-2023-Copy.pdf\">Water effect on the oxygen reduction reaction for anion exchange membrane fuel cells<\/a><\/p>\n\n\n\n<p><br> Zoom <\/p>\n\n\n\n<p>Join Zoom Meeting:<\/p>\n\n\n\n<p><a href=\"https:\/\/technion.zoom.us\/j\/95988816357\">https:\/\/technion.zoom.us\/j\/95988816357<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seminar by Zihua Chen on: Water effect on the oxygen reduction reaction for anion exchange membrane fuel cells Zoom Join Zoom Meeting: https:\/\/technion.zoom.us\/j\/95988816357<\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[10,43],"tags":[],"class_list":["post-55546","post","type-post","status-publish","format-standard","hentry","category-seminars","category-seminars_he"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Seminar by   Zihua Chen - The Wolfson Department of Chemical Engineering<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seminar by   Zihua Chen - The Wolfson Department of Chemical Engineering\" \/>\n<meta property=\"og:description\" content=\"Seminar by Zihua Chen on: Water effect on the oxygen reduction reaction for anion exchange membrane fuel cells Zoom Join Zoom Meeting: https:\/\/technion.zoom.us\/j\/95988816357\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/\" \/>\n<meta property=\"og:site_name\" content=\"The Wolfson Department of Chemical Engineering\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-26T23:47:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-26T23:47:14+00:00\" \/>\n<meta name=\"author\" content=\"ce.dean.ad\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ce.dean.ad\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/\"},\"author\":{\"name\":\"ce.dean.ad\",\"@id\":\"https:\/\/chemeng.technion.ac.il\/#\/schema\/person\/dc0e492069f019bf8e55c29c6ac38226\"},\"headline\":\"Seminar by Zihua Chen\",\"datePublished\":\"2023-10-26T23:47:11+00:00\",\"dateModified\":\"2023-10-26T23:47:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/\"},\"wordCount\":31,\"publisher\":{\"@id\":\"https:\/\/chemeng.technion.ac.il\/#organization\"},\"articleSection\":[\"Seminars\",\"\u05e1\u05de\u05d9\u05e0\u05e8\u05d9\u05dd\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/\",\"url\":\"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/\",\"name\":\"Seminar by Zihua Chen - The Wolfson Department of Chemical Engineering\",\"isPartOf\":{\"@id\":\"https:\/\/chemeng.technion.ac.il\/#website\"},\"datePublished\":\"2023-10-26T23:47:11+00:00\",\"dateModified\":\"2023-10-26T23:47:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/chemeng.technion.ac.il\/en\/new-home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seminar by Zihua Chen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chemeng.technion.ac.il\/#website\",\"url\":\"https:\/\/chemeng.technion.ac.il\/\",\"name\":\"The Wolfson Department of Chemical Engineering\",\"description\":\"Upgrading Nature\",\"publisher\":{\"@id\":\"https:\/\/chemeng.technion.ac.il\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chemeng.technion.ac.il\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/chemeng.technion.ac.il\/#organization\",\"name\":\"\u05d4\u05e4\u05e7\u05d5\u05dc\u05d8\u05d4 \u05dc\u05d4\u05e0\u05d3\u05e1\u05d4 \u05db\u05d9\u05de\u05d9\u05ea \u05e2\\\"\u05e9 \u05d5\u05d5\u05dc\u05e4\u05e1\u05d5\u05df\",\"url\":\"https:\/\/chemeng.technion.ac.il\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/chemeng.technion.ac.il\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/chemeng.technion.ac.il\/wp-content\/uploads\/2023\/05\/logo-faculty-he.png\",\"contentUrl\":\"https:\/\/chemeng.technion.ac.il\/wp-content\/uploads\/2023\/05\/logo-faculty-he.png\",\"width\":219,\"height\":81,\"caption\":\"\u05d4\u05e4\u05e7\u05d5\u05dc\u05d8\u05d4 \u05dc\u05d4\u05e0\u05d3\u05e1\u05d4 \u05db\u05d9\u05de\u05d9\u05ea \u05e2\\\"\u05e9 \u05d5\u05d5\u05dc\u05e4\u05e1\u05d5\u05df\"},\"image\":{\"@id\":\"https:\/\/chemeng.technion.ac.il\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/chemeng.technion.ac.il\/#\/schema\/person\/dc0e492069f019bf8e55c29c6ac38226\",\"name\":\"ce.dean.ad\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/chemeng.technion.ac.il\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e71d2ecd723d5f55160f3b4c34c5f3301515a5b16d89b2e07bab047d758b66bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e71d2ecd723d5f55160f3b4c34c5f3301515a5b16d89b2e07bab047d758b66bc?s=96&d=mm&r=g\",\"caption\":\"ce.dean.ad\"},\"url\":\"https:\/\/chemeng.technion.ac.il\/en\/author\/ce-dean-ad\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seminar by   Zihua Chen - The Wolfson Department of Chemical Engineering","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/","og_locale":"en_US","og_type":"article","og_title":"Seminar by   Zihua Chen - The Wolfson Department of Chemical Engineering","og_description":"Seminar by Zihua Chen on: Water effect on the oxygen reduction reaction for anion exchange membrane fuel cells Zoom Join Zoom Meeting: https:\/\/technion.zoom.us\/j\/95988816357","og_url":"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/","og_site_name":"The Wolfson Department of Chemical Engineering","article_published_time":"2023-10-26T23:47:11+00:00","article_modified_time":"2023-10-26T23:47:14+00:00","author":"ce.dean.ad","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ce.dean.ad","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/#article","isPartOf":{"@id":"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/"},"author":{"name":"ce.dean.ad","@id":"https:\/\/chemeng.technion.ac.il\/#\/schema\/person\/dc0e492069f019bf8e55c29c6ac38226"},"headline":"Seminar by Zihua Chen","datePublished":"2023-10-26T23:47:11+00:00","dateModified":"2023-10-26T23:47:14+00:00","mainEntityOfPage":{"@id":"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/"},"wordCount":31,"publisher":{"@id":"https:\/\/chemeng.technion.ac.il\/#organization"},"articleSection":["Seminars","\u05e1\u05de\u05d9\u05e0\u05e8\u05d9\u05dd"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/","url":"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/","name":"Seminar by Zihua Chen - The Wolfson Department of Chemical Engineering","isPartOf":{"@id":"https:\/\/chemeng.technion.ac.il\/#website"},"datePublished":"2023-10-26T23:47:11+00:00","dateModified":"2023-10-26T23:47:14+00:00","breadcrumb":{"@id":"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/chemeng.technion.ac.il\/en\/seminar-by-zihua-chen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chemeng.technion.ac.il\/en\/new-home\/"},{"@type":"ListItem","position":2,"name":"Seminar by Zihua Chen"}]},{"@type":"WebSite","@id":"https:\/\/chemeng.technion.ac.il\/#website","url":"https:\/\/chemeng.technion.ac.il\/","name":"The Wolfson Department of Chemical Engineering","description":"Upgrading Nature","publisher":{"@id":"https:\/\/chemeng.technion.ac.il\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chemeng.technion.ac.il\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/chemeng.technion.ac.il\/#organization","name":"\u05d4\u05e4\u05e7\u05d5\u05dc\u05d8\u05d4 \u05dc\u05d4\u05e0\u05d3\u05e1\u05d4 \u05db\u05d9\u05de\u05d9\u05ea \u05e2\"\u05e9 \u05d5\u05d5\u05dc\u05e4\u05e1\u05d5\u05df","url":"https:\/\/chemeng.technion.ac.il\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/chemeng.technion.ac.il\/#\/schema\/logo\/image\/","url":"https:\/\/chemeng.technion.ac.il\/wp-content\/uploads\/2023\/05\/logo-faculty-he.png","contentUrl":"https:\/\/chemeng.technion.ac.il\/wp-content\/uploads\/2023\/05\/logo-faculty-he.png","width":219,"height":81,"caption":"\u05d4\u05e4\u05e7\u05d5\u05dc\u05d8\u05d4 \u05dc\u05d4\u05e0\u05d3\u05e1\u05d4 \u05db\u05d9\u05de\u05d9\u05ea \u05e2\"\u05e9 \u05d5\u05d5\u05dc\u05e4\u05e1\u05d5\u05df"},"image":{"@id":"https:\/\/chemeng.technion.ac.il\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/chemeng.technion.ac.il\/#\/schema\/person\/dc0e492069f019bf8e55c29c6ac38226","name":"ce.dean.ad","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/chemeng.technion.ac.il\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e71d2ecd723d5f55160f3b4c34c5f3301515a5b16d89b2e07bab047d758b66bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e71d2ecd723d5f55160f3b4c34c5f3301515a5b16d89b2e07bab047d758b66bc?s=96&d=mm&r=g","caption":"ce.dean.ad"},"url":"https:\/\/chemeng.technion.ac.il\/en\/author\/ce-dean-ad\/"}]}},"_links":{"self":[{"href":"https:\/\/chemeng.technion.ac.il\/en\/wp-json\/wp\/v2\/posts\/55546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chemeng.technion.ac.il\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chemeng.technion.ac.il\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chemeng.technion.ac.il\/en\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/chemeng.technion.ac.il\/en\/wp-json\/wp\/v2\/comments?post=55546"}],"version-history":[{"count":3,"href":"https:\/\/chemeng.technion.ac.il\/en\/wp-json\/wp\/v2\/posts\/55546\/revisions"}],"predecessor-version":[{"id":55549,"href":"https:\/\/chemeng.technion.ac.il\/en\/wp-json\/wp\/v2\/posts\/55546\/revisions\/55549"}],"wp:attachment":[{"href":"https:\/\/chemeng.technion.ac.il\/en\/wp-json\/wp\/v2\/media?parent=55546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chemeng.technion.ac.il\/en\/wp-json\/wp\/v2\/categories?post=55546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chemeng.technion.ac.il\/en\/wp-json\/wp\/v2\/tags?post=55546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}